{"id":1120,"date":"2021-01-31T19:15:45","date_gmt":"2021-01-31T19:15:45","guid":{"rendered":"https:\/\/www.hop-m.org\/?p=1120"},"modified":"2021-01-31T19:20:05","modified_gmt":"2021-01-31T19:20:05","slug":"novita-cantiere-casa-di-preghiera","status":"publish","type":"post","link":"https:\/\/www.hop-m.org\/it\/novita-cantiere-casa-di-preghiera\/","title":{"rendered":"Novit\u00e0 cantiere casa di preghiera"},"content":{"rendered":"<p>Nelle ultime settimane\u00a0 molte cose sono andate avanti e la sala di preghiera sta prendendo forma. Siamo cos\u00ec grati a tutti coloro che stanno aiutando e spendono il loro tempo nel cantiere ogni giorno.<\/p>\n<p>Nonostante siamo ancora nella fase 1 (demolizione, ricostruzione, ecc.), ci stiamo avvicinando sempre di pi\u00f9 alla seconda fase nonostante ci sia ancora molto da fare.<br \/>\nIl carico di lavoro a volte \u00e9 pi\u00f9 intenso poich\u00e9 stiamo costruendo completamente con cartongesso, ma questo ci permette di isolare bene tutte le pareti e i soffitti acusticamente e anche termicamente . Ora che quasi tutto \u00e9 stato rivestito con Fermacell e con cartongesso, il pittore potr\u00e0 iniziare ad intonacare e successivamente imbiancare. In fine il pavimento verr\u00e0 completamente ricostruito.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mcusercontent.com\/165667d92aefb558d8b9c1578\/images\/b163bd6a-5f76-488f-85ec-4d76cf873831.png\" width=\"600\" height=\"450\" data-file-id=\"1746212\" data-cke-saved-src=\"https:\/\/mcusercontent.com\/165667d92aefb558d8b9c1578\/images\/b163bd6a-5f76-488f-85ec-4d76cf873831.png\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mcusercontent.com\/165667d92aefb558d8b9c1578\/images\/c418b036-8396-4b93-b4f0-2ecc4ebee630.png\" width=\"600\" height=\"800\" data-file-id=\"1746216\" data-cke-saved-src=\"https:\/\/mcusercontent.com\/165667d92aefb558d8b9c1578\/images\/c418b036-8396-4b93-b4f0-2ecc4ebee630.png\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mcusercontent.com\/165667d92aefb558d8b9c1578\/images\/014ec25d-baf8-4c7b-bbb5-2b4345afec69.png\" width=\"600\" height=\"450\" data-file-id=\"1746224\" data-cke-saved-src=\"https:\/\/mcusercontent.com\/165667d92aefb558d8b9c1578\/images\/014ec25d-baf8-4c7b-bbb5-2b4345afec69.png\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mcusercontent.com\/165667d92aefb558d8b9c1578\/images\/6f1afaf0-8c67-44af-8f04-c59f2d8b1e54.png\" width=\"600\" height=\"450\" data-file-id=\"1746232\" data-cke-saved-src=\"https:\/\/mcusercontent.com\/165667d92aefb558d8b9c1578\/images\/6f1afaf0-8c67-44af-8f04-c59f2d8b1e54.png\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mcusercontent.com\/165667d92aefb558d8b9c1578\/images\/103ca366-a441-4641-8b34-06f4b091c2da.png\" width=\"600\" height=\"450\" data-file-id=\"1746236\" data-cke-saved-src=\"https:\/\/mcusercontent.com\/165667d92aefb558d8b9c1578\/images\/103ca366-a441-4641-8b34-06f4b091c2da.png\" \/><\/p>\n<p><span style=\"color: #000000;\">Pi\u00f9 il lavoro procede, maggiori sono le spese come ad esempio per i materiali da costruzione, i singoli artigiani e altre spese generali.<\/span><\/p>\n<p><span style=\"color: #000000;\">Costruisci casa di preghiera con noi e semina nel regno di Dio.<\/span><\/p>\n<blockquote>\n<div>\n<p><strong><em>Tuttavia, chi semina soltanto pochi semi, avr\u00e0 un piccolo raccolto; mentre chi semina molto, mieter\u00e0 molto. 2 Corinzi 9.6<\/em><\/strong><\/p>\n<\/div>\n<\/blockquote>\n<p><span style=\"color: #000000;\"><em>Sostienici facendo un bonifico della tua donazione sul nostro conto corrente con il riferimento &#8220;donazione casa di preghiera&#8221; (cos\u00ec facendo possiamo rilasciarti una ricevuta di donazione) oppure clicca sul link sottostante per donare tramite PayPal.<\/em><\/span><\/p>\n<p><span style=\"color: #000000;\">HOP Merano \u2013 House of Prayer \u2013 Gebetshaus<\/span><br \/>\n<span style=\"color: #000000;\">IBAN: IT25D0811258590000301275119<\/span><br \/>\n<span style=\"color: #000000;\">SWIFT\/BIC: RZSBIT21201<\/span><\/p>\n<p><a href=\"https:\/\/www.hop-m.org\/it\/#sostenere\" target=\"_blank\" rel=\"noopener\" data-cke-saved-href=\"https:\/\/www.hop-m.org\/it\/#sostenere\">https:\/\/www.hop-m.org\/it\/#sostenere<\/a><\/p>\n<p>GRAZIE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nelle ultime settimane\u00a0 molte cose sono andate avanti e la sala di preghiera sta prendendo forma. Siamo cos\u00ec grati a tutti coloro che stanno aiutando e spendono il loro tempo nel cantiere ogni giorno. Nonostante siamo ancora nella fase 1 (demolizione, ricostruzione, ecc.), ci stiamo avvicinando sempre di pi\u00f9 alla seconda fase nonostante ci sia [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1115,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1120","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-categorizzato"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Novit\u00e0 cantiere casa di preghiera - HOP Merano Casa di Preghiera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hop-m.org\/it\/novita-cantiere-casa-di-preghiera\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novit\u00e0 cantiere casa di preghiera - HOP Merano Casa di Preghiera\" \/>\n<meta property=\"og:description\" content=\"Nelle ultime settimane\u00a0 molte cose sono andate avanti e la sala di preghiera sta prendendo forma. Siamo cos\u00ec grati a tutti coloro che stanno aiutando e spendono il loro tempo nel cantiere ogni giorno. Nonostante siamo ancora nella fase 1 (demolizione, ricostruzione, ecc.), ci stiamo avvicinando sempre di pi\u00f9 alla seconda fase nonostante ci sia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hop-m.org\/it\/novita-cantiere-casa-di-preghiera\/\" \/>\n<meta property=\"og:site_name\" content=\"HOP Merano Casa di Preghiera\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-31T19:15:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-31T19:20:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hop-m.org\/wp-content\/uploads\/2021\/01\/foto1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1030\" \/>\n\t<meta property=\"og:image:height\" content=\"773\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Devid\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Devid\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hop-m.org\\\/it\\\/novita-cantiere-casa-di-preghiera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hop-m.org\\\/it\\\/novita-cantiere-casa-di-preghiera\\\/\"},\"author\":{\"name\":\"Devid\",\"@id\":\"https:\\\/\\\/www.hop-m.org\\\/it\\\/#\\\/schema\\\/person\\\/995e4a212d17e4910f5b94f5b57e8ff5\"},\"headline\":\"Novit\u00e0 cantiere casa di preghiera\",\"datePublished\":\"2021-01-31T19:15:45+00:00\",\"dateModified\":\"2021-01-31T19:20:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hop-m.org\\\/it\\\/novita-cantiere-casa-di-preghiera\\\/\"},\"wordCount\":227,\"publisher\":{\"@id\":\"https:\\\/\\\/www.hop-m.org\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hop-m.org\\\/it\\\/novita-cantiere-casa-di-preghiera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hop-m.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/foto1.png\",\"articleSection\":[\"Non categorizzato\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hop-m.org\\\/it\\\/novita-cantiere-casa-di-preghiera\\\/\",\"url\":\"https:\\\/\\\/www.hop-m.org\\\/it\\\/novita-cantiere-casa-di-preghiera\\\/\",\"name\":\"Novit\u00e0 cantiere casa di preghiera - HOP Merano Casa di Preghiera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hop-m.org\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hop-m.org\\\/it\\\/novita-cantiere-casa-di-preghiera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hop-m.org\\\/it\\\/novita-cantiere-casa-di-preghiera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hop-m.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/foto1.png\",\"datePublished\":\"2021-01-31T19:15:45+00:00\",\"dateModified\":\"2021-01-31T19:20:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hop-m.org\\\/it\\\/novita-cantiere-casa-di-preghiera\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hop-m.org\\\/it\\\/novita-cantiere-casa-di-preghiera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.hop-m.org\\\/it\\\/novita-cantiere-casa-di-preghiera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hop-m.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/foto1.png\",\"contentUrl\":\"https:\\\/\\\/www.hop-m.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/foto1.png\",\"width\":1030,\"height\":773},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hop-m.org\\\/it\\\/novita-cantiere-casa-di-preghiera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.hop-m.org\\\/it\\\/hop-merano-casa-di-preghiera\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Novit\u00e0 cantiere casa di preghiera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hop-m.org\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.hop-m.org\\\/it\\\/\",\"name\":\"HOP Merano Casa di Preghiera\",\"description\":\"Casa di Preghiera Merano\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hop-m.org\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hop-m.org\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hop-m.org\\\/it\\\/#organization\",\"name\":\"HOP Meran Gebetshaus\",\"url\":\"https:\\\/\\\/www.hop-m.org\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.hop-m.org\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hop-m.org\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/HOP-Merano_Logo-Credits.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hop-m.org\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/HOP-Merano_Logo-Credits.jpg\",\"width\":1030,\"height\":687,\"caption\":\"HOP Meran Gebetshaus\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hop-m.org\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hop-m.org\\\/it\\\/#\\\/schema\\\/person\\\/995e4a212d17e4910f5b94f5b57e8ff5\",\"name\":\"Devid\",\"sameAs\":[\"https:\\\/\\\/www.hop-m.org\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Novit\u00e0 cantiere casa di preghiera - HOP Merano Casa di Preghiera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hop-m.org\/it\/novita-cantiere-casa-di-preghiera\/","og_locale":"it_IT","og_type":"article","og_title":"Novit\u00e0 cantiere casa di preghiera - HOP Merano Casa di Preghiera","og_description":"Nelle ultime settimane\u00a0 molte cose sono andate avanti e la sala di preghiera sta prendendo forma. Siamo cos\u00ec grati a tutti coloro che stanno aiutando e spendono il loro tempo nel cantiere ogni giorno. Nonostante siamo ancora nella fase 1 (demolizione, ricostruzione, ecc.), ci stiamo avvicinando sempre di pi\u00f9 alla seconda fase nonostante ci sia [&hellip;]","og_url":"https:\/\/www.hop-m.org\/it\/novita-cantiere-casa-di-preghiera\/","og_site_name":"HOP Merano Casa di Preghiera","article_published_time":"2021-01-31T19:15:45+00:00","article_modified_time":"2021-01-31T19:20:05+00:00","og_image":[{"width":1030,"height":773,"url":"https:\/\/www.hop-m.org\/wp-content\/uploads\/2021\/01\/foto1.png","type":"image\/png"}],"author":"Devid","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Devid","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hop-m.org\/it\/novita-cantiere-casa-di-preghiera\/#article","isPartOf":{"@id":"https:\/\/www.hop-m.org\/it\/novita-cantiere-casa-di-preghiera\/"},"author":{"name":"Devid","@id":"https:\/\/www.hop-m.org\/it\/#\/schema\/person\/995e4a212d17e4910f5b94f5b57e8ff5"},"headline":"Novit\u00e0 cantiere casa di preghiera","datePublished":"2021-01-31T19:15:45+00:00","dateModified":"2021-01-31T19:20:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hop-m.org\/it\/novita-cantiere-casa-di-preghiera\/"},"wordCount":227,"publisher":{"@id":"https:\/\/www.hop-m.org\/it\/#organization"},"image":{"@id":"https:\/\/www.hop-m.org\/it\/novita-cantiere-casa-di-preghiera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hop-m.org\/wp-content\/uploads\/2021\/01\/foto1.png","articleSection":["Non categorizzato"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.hop-m.org\/it\/novita-cantiere-casa-di-preghiera\/","url":"https:\/\/www.hop-m.org\/it\/novita-cantiere-casa-di-preghiera\/","name":"Novit\u00e0 cantiere casa di preghiera - HOP Merano Casa di Preghiera","isPartOf":{"@id":"https:\/\/www.hop-m.org\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hop-m.org\/it\/novita-cantiere-casa-di-preghiera\/#primaryimage"},"image":{"@id":"https:\/\/www.hop-m.org\/it\/novita-cantiere-casa-di-preghiera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hop-m.org\/wp-content\/uploads\/2021\/01\/foto1.png","datePublished":"2021-01-31T19:15:45+00:00","dateModified":"2021-01-31T19:20:05+00:00","breadcrumb":{"@id":"https:\/\/www.hop-m.org\/it\/novita-cantiere-casa-di-preghiera\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hop-m.org\/it\/novita-cantiere-casa-di-preghiera\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hop-m.org\/it\/novita-cantiere-casa-di-preghiera\/#primaryimage","url":"https:\/\/www.hop-m.org\/wp-content\/uploads\/2021\/01\/foto1.png","contentUrl":"https:\/\/www.hop-m.org\/wp-content\/uploads\/2021\/01\/foto1.png","width":1030,"height":773},{"@type":"BreadcrumbList","@id":"https:\/\/www.hop-m.org\/it\/novita-cantiere-casa-di-preghiera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.hop-m.org\/it\/hop-merano-casa-di-preghiera\/"},{"@type":"ListItem","position":2,"name":"Novit\u00e0 cantiere casa di preghiera"}]},{"@type":"WebSite","@id":"https:\/\/www.hop-m.org\/it\/#website","url":"https:\/\/www.hop-m.org\/it\/","name":"HOP Merano Casa di Preghiera","description":"Casa di Preghiera Merano","publisher":{"@id":"https:\/\/www.hop-m.org\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hop-m.org\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.hop-m.org\/it\/#organization","name":"HOP Meran Gebetshaus","url":"https:\/\/www.hop-m.org\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.hop-m.org\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.hop-m.org\/wp-content\/uploads\/2019\/04\/HOP-Merano_Logo-Credits.jpg","contentUrl":"https:\/\/www.hop-m.org\/wp-content\/uploads\/2019\/04\/HOP-Merano_Logo-Credits.jpg","width":1030,"height":687,"caption":"HOP Meran Gebetshaus"},"image":{"@id":"https:\/\/www.hop-m.org\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.hop-m.org\/it\/#\/schema\/person\/995e4a212d17e4910f5b94f5b57e8ff5","name":"Devid","sameAs":["https:\/\/www.hop-m.org"]}]}},"_links":{"self":[{"href":"https:\/\/www.hop-m.org\/it\/wp-json\/wp\/v2\/posts\/1120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hop-m.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hop-m.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hop-m.org\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hop-m.org\/it\/wp-json\/wp\/v2\/comments?post=1120"}],"version-history":[{"count":0,"href":"https:\/\/www.hop-m.org\/it\/wp-json\/wp\/v2\/posts\/1120\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hop-m.org\/it\/wp-json\/wp\/v2\/media\/1115"}],"wp:attachment":[{"href":"https:\/\/www.hop-m.org\/it\/wp-json\/wp\/v2\/media?parent=1120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hop-m.org\/it\/wp-json\/wp\/v2\/categories?post=1120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hop-m.org\/it\/wp-json\/wp\/v2\/tags?post=1120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}